{"id":13778,"date":"2024-05-25T14:36:34","date_gmt":"2024-05-25T12:36:34","guid":{"rendered":"https:\/\/caffeonline.ch\/produkt\/caffe-toraldo-capsule-caffe-e-ginseng\/"},"modified":"2025-02-07T22:41:24","modified_gmt":"2025-02-07T21:41:24","slug":"caffe-toraldo-capsule-caffe-e-ginseng","status":"publish","type":"product","link":"https:\/\/caffeonline.aclas.io\/it\/produkt\/caffe-toraldo-capsule-caffe-e-ginseng\/","title":{"rendered":"Caff\u00e8 Toraldo &#8211; Capsule Caff\u00e8 e Ginseng"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Fai il pieno di energia con le <strong>capsule di Caff\u00e8 e Ginseng<\/strong> di <strong>Caff\u00e8 Toraldo<\/strong>. Questa bevanda combina il ricco sapore del caff\u00e8 con le propriet\u00e0 energizzanti del ginseng e offre una pausa caff\u00e8 che rivitalizza corpo e mente.<\/p>\n<p>Le <strong>capsule<\/strong> garantiscono una <strong>preparazione facile e veloce<\/strong>, cos\u00ec potrai gustare un caff\u00e8 al ginseng in pochi minuti.<\/p>\n","protected":false},"featured_media":13715,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[339,344,560,345],"product_tag":[],"class_list":{"0":"post-13778","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bevande-calde","7":"product_cat-capsule","8":"product_cat-offerte-speciali","9":"product_cat-sistema-dolce-gusto","10":"pa_brand-caffe-toraldo-it","11":"has-subscription-plans","13":"first","14":"outofstock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"batches":[{"id":"480","date_created":"2024-05-25 09:04:02","date_expiry":"2025-09-01 00:00:00","user_id":"559","batch_number":"","supplier":"","location":"","quantity":"1.0000","quantity_available":"0.0000","units":"1","status":"archived","order_ids":"[15743,132546112]","po":null},{"id":"972","date_created":"2024-11-07 18:11:35","date_expiry":"2026-03-30 00:00:00","user_id":"559","batch_number":"","supplier":"","location":"","quantity":"4.0000","quantity_available":"0.0000","units":"1","status":"archived","order_ids":"[132546112,132547047,132549586]","po":null}],"_links":{"self":[{"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/product\/13778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/comments?post=13778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/media\/13715"}],"wp:attachment":[{"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/media?parent=13778"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/product_brand?post=13778"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/product_cat?post=13778"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/caffeonline.aclas.io\/it\/wp-json\/wp\/v2\/product_tag?post=13778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}